{"id":261,"date":"2017-12-13T14:27:29","date_gmt":"2017-12-13T16:27:29","guid":{"rendered":"http:\/\/patricialacombe.com.br\/blog\/?p=261"},"modified":"2019-05-29T13:43:31","modified_gmt":"2019-05-29T16:43:31","slug":"conheca-a-diferenca-entre-ginastica-holistica-e-rpg-2","status":"publish","type":"post","link":"http:\/\/patricialacombe.com.br\/blog\/conheca-a-diferenca-entre-ginastica-holistica-e-rpg-2\/","title":{"rendered":"Conhe\u00e7a a diferen\u00e7a entre gin\u00e1stica hol\u00edstica e RPG"},"content":{"rendered":"<p>Os cuidados com o corpo e com a mente devem come\u00e7ar cedo para que tenhamos longevidade e qualidade de vida.<\/p>\n<p>Alguns dos grandes dist\u00farbios sofridos\u00a0pelos brasileiros, em raz\u00e3o\u00a0da falta de uma aten\u00e7\u00e3o adequada, s\u00e3o os problemas posturais, principalmente aqueles relacionados ao estresse do trabalho. No dia a dia, essa m\u00e1 postura ocasiona\u00a0dores e compromete\u00a0o desempenho de diversas atividades.<\/p>\n<p>Mas saiba que\u00a0h\u00e1 solu\u00e7\u00e3o: existem\u00a0m\u00e9todos que visam corrigir a postura, proporcionando a conquista do\u00a0bem-estar.<\/p>\n<p>No post de hoje, voc\u00ea vai entender a diferen\u00e7a entre gin\u00e1stica hol\u00edstica e RPG, dois m\u00e9todos que especializados na\u00a0melhoria da sa\u00fade postural.<\/p>\n<p>Continue a leitura e saiba mais!<\/p>\n<h2>Saiba o que \u00e9 a gin\u00e1stica hol\u00edstica<\/h2>\n<p>Vamos come\u00e7ar falando da gin\u00e1stica hol\u00edstica.<\/p>\n<p>Essa modalidade tem o objetivo de trabalhar o corpo como um todo, com o intuito de promover o alinhamento da postura e, dessa forma, evitar dores.<\/p>\n<p>Esse m\u00e9todo foi criado pela m\u00e9dica e terapeuta alem\u00e3 Lily Ehrenfried e tem se tornado popular no Brasil, atraindo pessoas interessadas em tratar e prevenir diversos tipos de les\u00f5es causadas por esfor\u00e7os repetitivos, h\u00e9rnias e tamb\u00e9m dores corriqueiras na regi\u00e3o das\u00a0costas.<\/p>\n<p>A gin\u00e1stica hol\u00edstica \u00e9 baseada em tr\u00eas pilares.\u00a0S\u00e3o eles: educa\u00e7\u00e3o, preven\u00e7\u00e3o e tratamento.<\/p>\n<p>Desse modo,\u00a0o trabalho visa estimular a consci\u00eancia corporal, o que significa tamb\u00e9m a execu\u00e7\u00e3o correta de movimentos que s\u00e3o feitos no dia a dia e, principalmente, o al\u00edvio de tens\u00f5es.<\/p>\n<h2>Conhe\u00e7a as principais caracter\u00edsticas do m\u00e9todo RPG<\/h2>\n<p>Agora, seguimos com o RPG, ou reeduca\u00e7\u00e3o postural global.\u00a0<\/p>\n<p>Esse m\u00e9todo foi criado pelo fisioterapeuta franc\u00eas Philippe Souchard, a partir de estudos de f\u00edsica e biomec\u00e2nica.\u00a0<\/p>\n<p>Aplica-se a diversas patologias que requerem o tratamento fisioterap\u00eautico, tendo\u00a0como base tr\u00eas\u00a0princ\u00edpios fundamentais.<\/p>\n<p>S\u00e3o eles: a individualidade, que \u00e9 a forma como cada ser humano reage de formas diferentes; a casualidade, que entende que a real causa do problema nem sempre est\u00e1 perto do sintoma (causa\/consequ\u00eancia);\u00a0a globalidade, que trata o corpo como um todo e busca identificar a responsabilidade das retra\u00e7\u00f5es musculares.<\/p>\n<h2>Entenda a diferen\u00e7a entre gin\u00e1stica hol\u00edstica e RPG<\/h2>\n<p>Ambos os m\u00e9todos trabalham com a reabilita\u00e7\u00e3o da postura. Entretanto, a diferen\u00e7a entre gin\u00e1stica hol\u00edstica e RPG est\u00e1 no dinamismo.<\/p>\n<p>A gin\u00e1stica hol\u00edstica proporciona muito mais autonomia ao aluno e, ao longo das aulas, utiliza mais de 800 movimentos globais que proporcionam a melhoria da respira\u00e7\u00e3o e do\u00a0t\u00f4nus muscular, colocando o corpo em equil\u00edbrio com sua funcionalidade.<\/p>\n<p>A t\u00e9cnica mexe com toda a musculatura profunda do corpo, e n\u00e3o h\u00e1 contraindica\u00e7\u00e3o para a sua pr\u00e1tica.<\/p>\n<p>O m\u00e9todo RPG, por ter din\u00e2mica de atividade mais lenta, muitas vezes, causa monotonia nos alunos.\u00a0<\/p>\n<p>Outra diferen\u00e7a essencial \u00e9 que o RPG exige supervis\u00e3o constante, em raz\u00e3o dos princ\u00edpios de sua pr\u00e1tica. \u00a0<\/p>\n<p>Assim, diferentemente da\u00a0gin\u00e1stica hol\u00edstica, na qual o aluno pode reproduzir os movimentos em casa ap\u00f3s a aula, o RPG n\u00e3o permite tanta independ\u00eancia no desenvolvimento do programa.\u00a0<\/p>\n<h2>Vantagens da gin\u00e1stica hol\u00edstica\u00a0<\/h2>\n<p>Como citamos acima, os cuidados com o corpo e com a mente devem come\u00e7ar desde cedo. Nesse sentido, a gin\u00e1stica hol\u00edstica \u00e9 uma excelente aliada, pois\u00a0age na preven\u00e7\u00e3o de diversas doen\u00e7as relacionadas \u00e0 m\u00e1 postura.<\/p>\n<p>Entre os benef\u00edcios, destacamos a reorganiza\u00e7\u00e3o postural e o equil\u00edbrio do t\u00f4nus muscular. Al\u00e9m disso, o m\u00e9todo faz com que a respira\u00e7\u00e3o do aluno fique cada vez mais natural e condizente com cada momento do seu dia.<\/p>\n<p>Muito usada nas \u00e1reas de ortopedia, neurologia e reumatologia, a gin\u00e1stica hol\u00edstica tamb\u00e9m pode ser uma alternativa para os per\u00edodos de gravidez e p\u00f3s-parto, com o objetivo de auxiliar o organismo no processo de adapta\u00e7\u00e3o de peso e respira\u00e7\u00e3o.<\/p>\n<p>Os exerc\u00edcios tamb\u00e9m s\u00e3o indicados para <a href=\"http:\/\/patricialacombe.com.br\/blog\/?p=111\">crian\u00e7as<\/a>,\u00a0favorecendo a conquista de flexibilidade, harmonia corporal e precis\u00e3o.<\/p>\n<p>Agora que voc\u00ea j\u00e1 sabe a diferen\u00e7a entre gin\u00e1stica hol\u00edstica e RPG para cuidar da sua sa\u00fade, <a href=\"http:\/\/patricialacombe.com.br\/contato\">entre em contato conosco<\/a>\u00a0para fazer uma avalia\u00e7\u00e3o!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os cuidados com o corpo e com a mente devem come\u00e7ar cedo para que tenhamos longevidade e qualidade de vida. Alguns dos grandes dist\u00farbios sofridos\u00a0pelos brasileiros, em raz\u00e3o\u00a0da falta de uma aten\u00e7\u00e3o adequada, s\u00e3o os problemas posturais, principalmente aqueles relacionados ao estresse do trabalho. No dia a dia, essa m\u00e1 postura ocasiona\u00a0dores e compromete\u00a0o desempenho<a class=\"moretag\" href=\"http:\/\/patricialacombe.com.br\/blog\/conheca-a-diferenca-entre-ginastica-holistica-e-rpg-2\/\"><span class=\"screen-reader-text\">Leia mais sobreConhe\u00e7a a diferen\u00e7a entre gin\u00e1stica hol\u00edstica e RPG<\/span>[&#8230;]<\/a><\/p>\n","protected":false},"author":5,"featured_media":262,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"_links":{"self":[{"href":"http:\/\/patricialacombe.com.br\/blog\/wp-json\/wp\/v2\/posts\/261"}],"collection":[{"href":"http:\/\/patricialacombe.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/patricialacombe.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/patricialacombe.com.br\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"http:\/\/patricialacombe.com.br\/blog\/wp-json\/wp\/v2\/comments?post=261"}],"version-history":[{"count":1,"href":"http:\/\/patricialacombe.com.br\/blog\/wp-json\/wp\/v2\/posts\/261\/revisions"}],"predecessor-version":[{"id":516,"href":"http:\/\/patricialacombe.com.br\/blog\/wp-json\/wp\/v2\/posts\/261\/revisions\/516"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/patricialacombe.com.br\/blog\/wp-json\/wp\/v2\/media\/262"}],"wp:attachment":[{"href":"http:\/\/patricialacombe.com.br\/blog\/wp-json\/wp\/v2\/media?parent=261"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/patricialacombe.com.br\/blog\/wp-json\/wp\/v2\/categories?post=261"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/patricialacombe.com.br\/blog\/wp-json\/wp\/v2\/tags?post=261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}